{"id":337,"count":2,"description":"","link":"https:\/\/ioleggoletichetta.it\/index.php\/tag\/uova\/","name":"uova","slug":"uova","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/ioleggoletichetta.it\/index.php\/wp-json\/wp\/v2\/tags\/337"}],"collection":[{"href":"https:\/\/ioleggoletichetta.it\/index.php\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/ioleggoletichetta.it\/index.php\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/ioleggoletichetta.it\/index.php\/wp-json\/wp\/v2\/posts?tags=337"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}